{"id":459,"date":"2017-12-06T09:31:39","date_gmt":"2017-12-06T09:31:39","guid":{"rendered":"http:\/\/explore.tetra.net\/?page_id=459"},"modified":"2025-02-07T12:09:06","modified_gmt":"2025-02-07T12:09:06","slug":"home","status":"publish","type":"page","link":"https:\/\/blog.tetra.net\/pl-pl\/","title":{"rendered":"Home"},"content":{"rendered":"\n<div class=\"slider-wrapper relative\" id=\"slider-1133838643\" style=\"background-color:rgb(255, 255, 255);\">\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-dark slider-nav-outside slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover\" id=\"banner-1944257675\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-654493662\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h3 class=\"uppercase\"><strong><span class=\"TextRun SCXW43266817 BCX8\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SpellingErrorV2Themed SpellingErrorHighlight SCXW43266817 BCX8\">Bezproblemowa<\/span> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW43266817 BCX8\">piel\u0119gnacja<\/span> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW43266817 BCX8\">oczka<\/span> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW43266817 BCX8\">wodnego<\/span> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW43266817 BCX8\">zaczyna<\/span> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW43266817 BCX8\">si\u0119<\/span> <span class=\"NormalTextRun SCXW43266817 BCX8\">od<\/span> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW43266817 BCX8\">sprawdzonych<\/span> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW43266817 BCX8\">produkt\u00f3w<\/span><span class=\"NormalTextRun SCXW43266817 BCX8\"> Tetra<\/span><\/span><\/strong><\/h3>\n<a href=\"https:\/\/blog.tetra.net\/pl-pl\/bezproblemowa-pielegnacja-oczka-wodnego-zaczyna-sie-od-sprawdzonych-produktow-tetra\/\" target=\"_self\" class=\"button primary\"  >\n    <span>Sprawd\u017a<\/span>\n  <\/a>\n\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-654493662 {\n  width: 87%;\n}\n#text-box-654493662 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1944257675 {\n  padding-top: 500px;\n}\n#banner-1944257675 .bg.bg-loaded {\n  background-image: url(https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2025\/02\/Blog_Pics_Pond_CAREvolution_1920x10805-1400x788.jpg);\n}\n#banner-1944257675 .bg {\n  background-position: 95% 95%;\n}\n#banner-1944257675 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1944257675 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1614453727\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1676981876\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"entry-title uppercase\">Kluczowe parametry wody stawowej<\/h2>\n<p>R\u00f3wnowaga biologiczna i jej utrzymywanie to podstawa pi\u0119knego oczka wodnego. A wszystko zaczyna si\u0119 od wody.<\/p>\n<a href=\"https:\/\/blog.tetra.net\/pl-pl\/kluczowe-parametry-wody-stawowej\/\" target=\"_self\" class=\"button white is-outline\"  >\n    <span>Dowiedz si\u0119 wi\u0119cej<\/span>\n  <\/a>\n\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1676981876 {\n  width: 96%;\n}\n#text-box-1676981876 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1676981876 {\n    width: 46%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1676981876 {\n    width: 32%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1614453727 {\n  padding-top: 400px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1614453727 .bg.bg-loaded {\n  background-image: url(https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/kluczowe-parametry-wody-stawowej.jpg);\n}\n#banner-1614453727 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n#banner-1614453727 .bg {\n  background-position: 57% 75%;\n}\n#banner-1614453727 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1614453727 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1252624455\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-724908498\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"-3\" data-parallax-fade=\"true\">                  <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><span style=\"color: #ffffff;\"><strong>Glony w oczku wodnym <\/strong><strong><\/strong><\/span><\/h2>\n<p><span style=\"color: #ffffff;\">Je\u015bli cokolwiek mo\u017ce zepsu\u0107 odpoczynek w ogrodzie na brzegu oczka wodnego, to s\u0105 to zdecydowanie glony&#8230;\u00a0<\/span><\/p>\n<a href=\"https:\/\/blog.tetra.net\/pl-pl\/glony-w-oczku-wodnym\/\" target=\"_self\" class=\"button white is-outline\"  >\n    <span>Sprawd\u017a<\/span>\n  <\/a>\n\n\n\n              <\/div>\n           <\/div>\n              <\/div>              \n<style>\n#text-box-724908498 {\n  width: 97%;\n}\n#text-box-724908498 .text-box-content {\n  font-size: 88%;\n}\n@media (min-width:550px) {\n  #text-box-724908498 {\n    width: 45%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-724908498 {\n    width: 50%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1252624455 {\n  padding-top: 400px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1252624455 .bg.bg-loaded {\n  background-image: url(https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/glony-w-oczku-wodnym.jpg);\n}\n#banner-1252624455 .overlay {\n  background-color: rgba(0, 0, 0, 0.4);\n}\n#banner-1252624455 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1252624455 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n<div class=\"container section-title-container\" style=\"margin-top:40px;\"><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Akwarium<\/span><b><\/b><\/h3><\/div>\n\n\n  \n    <div class=\"row large-columns-4 medium-columns-4 small-columns-1 row-small slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/twoje-pierwsze-akwarium\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/twoje-pierwsze-akwarium-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/twoje-pierwsze-akwarium-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/twoje-pierwsze-akwarium-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/twoje-pierwsze-akwarium.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Twoje pierwsze akwarium<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/twoje-pierwsze-akwarium\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/kojacy-wplyw-akwarium\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/kojacy-wplyw-akwarium-711x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/kojacy-wplyw-akwarium-711x400.jpg 711w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/kojacy-wplyw-akwarium-768x432.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/kojacy-wplyw-akwarium.jpg 869w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Koj\u0105cy wp\u0142yw akwarium<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/kojacy-wplyw-akwarium\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/przygotowanie-akwarium-przed-wyjazdem\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/przygotowanie-akwarium-przed-wyjazdem-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/przygotowanie-akwarium-przed-wyjazdem-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/przygotowanie-akwarium-przed-wyjazdem-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/przygotowanie-akwarium-przed-wyjazdem.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Przygotowanie akwarium przed wyjazdem<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/przygotowanie-akwarium-przed-wyjazdem\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/akwaria-rozbudzaja-wyobraznie-dzieci\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/akwaria-rozbudzaja-wyobraznie-dzieci-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/akwaria-rozbudzaja-wyobraznie-dzieci-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/akwaria-rozbudzaja-wyobraznie-dzieci-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/akwaria-rozbudzaja-wyobraznie-dzieci.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">\u201cAkwaria rozbudzaj\u0105 wyobra\u017ani\u0119 dzieci\u201d<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/akwaria-rozbudzaja-wyobraznie-dzieci\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/akwarium-dla-dziecka\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/akwarium-dla-dziecka-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/akwarium-dla-dziecka-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/akwarium-dla-dziecka-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/akwarium-dla-dziecka.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Akwarium dla dziecka<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/akwarium-dla-dziecka\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/rozmowa-ryba\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"196\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/rozmowa-ryba2.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Rozmowa z\u2026ryb\u0105?<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/rozmowa-ryba\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/zwierzeta-towarzyszace-obnizaja-szkolny-stres\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/zwierzeta-towarzyszace-obnizaja-szkolny-stres-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/zwierzeta-towarzyszace-obnizaja-szkolny-stres-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/zwierzeta-towarzyszace-obnizaja-szkolny-stres-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/zwierzeta-towarzyszace-obnizaja-szkolny-stres.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Zwierz\u0119ta towarzysz\u0105ce obni\u017caj\u0105 szkolny stres<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/zwierzeta-towarzyszace-obnizaja-szkolny-stres\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/ryby-jako-pracownicy-socjalni\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/ryby-jako-pracownicy-socjalni-711x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/ryby-jako-pracownicy-socjalni-711x400.jpg 711w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/ryby-jako-pracownicy-socjalni-768x432.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/ryby-jako-pracownicy-socjalni.jpg 869w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Ryby jako pracownicy socjalni<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/ryby-jako-pracownicy-socjalni\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n  \n    <div class=\"row large-columns-2 medium-columns-2 small-columns-1 row-small\">\n  <\/div>\n\n<div class=\"container section-title-container\" style=\"margin-top:40px;\"><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Oczko Wodne<\/span><b><\/b><\/h3><\/div>\n\n\n  \n    <div class=\"row large-columns-4 medium-columns-4 small-columns-1 row-small slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/bezproblemowa-pielegnacja-oczka-wodnego-zaczyna-sie-od-sprawdzonych-produktow-tetra\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2025\/02\/Blog_Pics_Pond_CAREvolution_1920x10805-711x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2025\/02\/Blog_Pics_Pond_CAREvolution_1920x10805-711x400.jpg 711w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2025\/02\/Blog_Pics_Pond_CAREvolution_1920x10805-1400x788.jpg 1400w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2025\/02\/Blog_Pics_Pond_CAREvolution_1920x10805-768x432.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2025\/02\/Blog_Pics_Pond_CAREvolution_1920x10805-1536x864.jpg 1536w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2025\/02\/Blog_Pics_Pond_CAREvolution_1920x10805.jpg 1920w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Bezproblemowa piel\u0119gnacja oczka wodnego zaczyna si\u0119 od sprawdzonych produkt\u00f3w Tetra\u00a0<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/bezproblemowa-pielegnacja-oczka-wodnego-zaczyna-sie-od-sprawdzonych-produktow-tetra\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/zabezpiecz-oczko-wodne-przed-zima\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/zabezpiecz-oczko-wodne-przed-zima-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/zabezpiecz-oczko-wodne-przed-zima-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/zabezpiecz-oczko-wodne-przed-zima-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/zabezpiecz-oczko-wodne-przed-zima.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Zabezpiecz oczko wodne przed zim\u0105<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/zabezpiecz-oczko-wodne-przed-zima\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/sezon-zimowy-w-oczku-wodnym\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/sezon-zimowy-w-oczku-wodnym-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/sezon-zimowy-w-oczku-wodnym-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/sezon-zimowy-w-oczku-wodnym-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/sezon-zimowy-w-oczku-wodnym.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Sezon zimowy w oczku wodnym<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/sezon-zimowy-w-oczku-wodnym\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/jak-dbac-o-zdrowie-ryb-stawowych-wiosna\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/jak-dbac-o-zdrowie-ryb-stawowych-wiosna-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/jak-dbac-o-zdrowie-ryb-stawowych-wiosna-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/jak-dbac-o-zdrowie-ryb-stawowych-wiosna-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/jak-dbac-o-zdrowie-ryb-stawowych-wiosna.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Jak dba\u0107 o zdrowie ryb stawowych wiosn\u0105?<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/jak-dbac-o-zdrowie-ryb-stawowych-wiosna\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/glony-zawiesinowe-czyli-zielona-woda-w-oczku-wodnym\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/glony-zawiesinowe-czyli-zielona-woda-w-oczku-wodnym-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/glony-zawiesinowe-czyli-zielona-woda-w-oczku-wodnym-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/glony-zawiesinowe-czyli-zielona-woda-w-oczku-wodnym-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/glony-zawiesinowe-czyli-zielona-woda-w-oczku-wodnym.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Glony zawiesinowe, czyli zielona woda w oczku wodnym<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/glony-zawiesinowe-czyli-zielona-woda-w-oczku-wodnym\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/glony-w-oczku-wodnym\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/glony-w-oczku-wodnym-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"glony w oczku wodnym\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/glony-w-oczku-wodnym-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/glony-w-oczku-wodnym-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/glony-w-oczku-wodnym.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Glony w oczku wodnym<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/glony-w-oczku-wodnym\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/blog.tetra.net\/pl-pl\/kluczowe-parametry-wody-stawowej\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"400\" src=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/kluczowe-parametry-wody-stawowej-727x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"kluczowe parametry wody stawowej\" srcset=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/kluczowe-parametry-wody-stawowej-727x400.jpg 727w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/kluczowe-parametry-wody-stawowej-768x422.jpg 768w, https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2019\/05\/kluczowe-parametry-wody-stawowej.jpg 1000w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0,0,0,.25)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-larger \">Woda w oczku wodnym \u2013 na jakie parametry nale\u017cy zwr\u00f3ci\u0107 uwag\u0119?<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/blog.tetra.net\/pl-pl\/kluczowe-parametry-wody-stawowej\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead article\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n<div class=\"container section-title-container\" style=\"margin-top:40px;\"><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Ro\u015bliny<\/span><b><\/b><\/h3><\/div>\n\n<div class=\"container section-title-container\" style=\"margin-top:40px;\"><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Ryby<\/span><b><\/b><\/h3><\/div>\n\n\n  \n    <div class=\"row large-columns-4 medium-columns-4 small-columns-1 row-small slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  <\/div>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":11,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-459","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home | Tetra Advanced Fishkeeper Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.tetra.net\/pl-pl\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home | Tetra Advanced Fishkeeper Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.tetra.net\/pl-pl\/\" \/>\n<meta property=\"og:site_name\" content=\"Tetra Advanced Fishkeeper Blog\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-07T12:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/\",\"url\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/\",\"name\":\"Home | Tetra Advanced Fishkeeper Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/dummy-1.jpg\",\"datePublished\":\"2017-12-06T09:31:39+00:00\",\"dateModified\":\"2025-02-07T12:09:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/dummy-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/dummy-1.jpg\",\"width\":400,\"height\":260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/#website\",\"url\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/\",\"name\":\"Tetra advanced fishkeeper blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.tetra.net\\\/pl-pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home | Tetra Advanced Fishkeeper Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.tetra.net\/pl-pl\/","og_locale":"en_GB","og_type":"article","og_title":"Home | Tetra Advanced Fishkeeper Blog","og_url":"https:\/\/blog.tetra.net\/pl-pl\/","og_site_name":"Tetra Advanced Fishkeeper Blog","article_modified_time":"2025-02-07T12:09:06+00:00","og_image":[{"width":400,"height":260,"url":"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2016\/08\/dummy-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.tetra.net\/pl-pl\/","url":"https:\/\/blog.tetra.net\/pl-pl\/","name":"Home | Tetra Advanced Fishkeeper Blog","isPartOf":{"@id":"https:\/\/blog.tetra.net\/pl-pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.tetra.net\/pl-pl\/#primaryimage"},"image":{"@id":"https:\/\/blog.tetra.net\/pl-pl\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2016\/08\/dummy-1.jpg","datePublished":"2017-12-06T09:31:39+00:00","dateModified":"2025-02-07T12:09:06+00:00","breadcrumb":{"@id":"https:\/\/blog.tetra.net\/pl-pl\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.tetra.net\/pl-pl\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/blog.tetra.net\/pl-pl\/#primaryimage","url":"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2016\/08\/dummy-1.jpg","contentUrl":"https:\/\/blog.tetra.net\/pl-pl\/wp-content\/uploads\/2016\/08\/dummy-1.jpg","width":400,"height":260},{"@type":"BreadcrumbList","@id":"https:\/\/blog.tetra.net\/pl-pl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.tetra.net\/pl-pl\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/blog.tetra.net\/pl-pl\/#website","url":"https:\/\/blog.tetra.net\/pl-pl\/","name":"Tetra advanced fishkeeper blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.tetra.net\/pl-pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/blog.tetra.net\/pl-pl\/wp-json\/wp\/v2\/pages\/459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tetra.net\/pl-pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blog.tetra.net\/pl-pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tetra.net\/pl-pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tetra.net\/pl-pl\/wp-json\/wp\/v2\/comments?post=459"}],"version-history":[{"count":74,"href":"https:\/\/blog.tetra.net\/pl-pl\/wp-json\/wp\/v2\/pages\/459\/revisions"}],"predecessor-version":[{"id":2120,"href":"https:\/\/blog.tetra.net\/pl-pl\/wp-json\/wp\/v2\/pages\/459\/revisions\/2120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.tetra.net\/pl-pl\/wp-json\/wp\/v2\/media\/11"}],"wp:attachment":[{"href":"https:\/\/blog.tetra.net\/pl-pl\/wp-json\/wp\/v2\/media?parent=459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}